{"id":35619,"date":"2026-02-09T22:29:37","date_gmt":"2026-02-09T21:29:37","guid":{"rendered":"https:\/\/jaimeconcept.ch\/?post_type=product&#038;p=35619"},"modified":"2026-05-30T15:13:03","modified_gmt":"2026-05-30T13:13:03","slug":"chaussettes-a-paillettes-rebelle","status":"publish","type":"product","link":"https:\/\/jaimeconcept.ch\/en\/product\/chaussettes-a-paillettes-rebelle\/","title":{"rendered":"Rebelle\u201c Sequined Socks\u201d"},"content":{"rendered":"<p>Chaussettes Woom :<\/p>\n<p>\u2714 Un Design brillant et tendance : Des paillettes subtiles pour un look chic et glamour.<\/p>\n<p>\u2714 Un Cadeau unique, personnalis\u00e9 qui fait sourire et qui fait passer un message !<\/p>\n<p>\u2714 Une Mati\u00e8re douce et respirante : Un M\u00e9lange de coton et fibres scintillantes pour un confort optimal. Les chaussettes \u00e0 paillettes allient confort et style.<\/p>\n<p>\u2714 Des Chaussettes Parfaites pour toutes occasions : Id\u00e9ales pour les journ\u00e9es cocooning, les soir\u00e9es entre amis ou en cadeau original.<\/p>\n<p>\u2714 Une Taille unique extensible : Con\u00e7ues pour s\u2019adapter parfaitement \u00e0 toutes les morphologies.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chaussettes \u00e0 taille unique 36\/40<\/p>\n<p>\ud83e\udde6 Qualit\u00e9 &#038; confort<\/p>\n<p>Composition : 60 % coton \u2013 35 % polyester \u2013 5 % \u00e9lasthanne<\/p>","protected":false},"featured_media":35610,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[436],"product_tag":[],"class_list":["post-35619","product","type-product","status-publish","has-post-thumbnail","product_cat-chaussettes","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/product\/35619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/comments?post=35619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/media\/35610"}],"wp:attachment":[{"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/media?parent=35619"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/product_brand?post=35619"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/product_cat?post=35619"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jaimeconcept.ch\/en\/wp-json\/wp\/v2\/product_tag?post=35619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}